{"id":1709,"date":"2022-04-15T16:59:12","date_gmt":"2022-04-15T14:59:12","guid":{"rendered":"http:\/\/hengstmanns.de\/WP\/?p=1709"},"modified":"2025-07-18T16:01:27","modified_gmt":"2025-07-18T14:01:27","slug":"von-halbleitern-und-halbkugeln","status":"publish","type":"post","link":"https:\/\/hengstmanns.de\/WP\/2022\/04\/15\/von-halbleitern-und-halbkugeln\/","title":{"rendered":"2021 &#8211; Von Halbleitern und Halbkugeln"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\">Das SommerOpenAirSpektakelKabarettTheater-St\u00fcck 2022 Im Magdeburger Technikmuseum<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#006600\"><strong>Vom 9. Juni bis 16. Juli 2022<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da soll es doch Menschen geben in Deutschland, wenn man die fragt:&nbsp; \u201eHaben sie schon mal etwas von Magdeburg geh\u00f6rt?\u201c, dann bekommt man meistens zur Antwort: \u201eGeh\u00f6rt? Irgendwie ja!\u201c Als Nachsatz aber h\u00f6rt man oft die Meinung: \u201eAlso freiwillig m\u00f6chte da nicht hin. Die in Magdeburg machen doch seit Jahrhunderten nur halbe Sachen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Beispiele werden dann benannt: Die Magdeburger Halbkugeln. Der grausame Fusel \u201eHalb und Halb\u201c, gebraut von einer Magdeburger Fuselschmiede. In den Eisdielen gab es haupts\u00e4chlich \u201eHalb\u201cgefrorenes Eis, bedingt durch die Energieknappheit in der Stadt war man damals selten in der Lage, richtiges Eis herzustellen. Durch Magdeburg schl\u00e4ngelt sich in s\u00fcdlicher Richtung die \u201eHalb\u201c- erst\u00e4dter Stra\u00dfe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So k\u00f6nnte man noch viele Beispiele anf\u00fchren, die die permanenten Halbheiten in Magdeburg bef\u00f6rdern. Doch damit soll endlich Schluss sein. Die Stadt k\u00e4mpft seit vielen Jahren darum, sich zur \u201eBOOMTOWN\u201c zu entwickeln. Und diese Stadt scheint den richtigen Kurs eingeschlagen zu haben. Nationale und internationale Gro\u00dfunternehmen haben und werden sich in und Magdeburg ansiedeln. Aldi ist l\u00e4ngst da. Da kann man sich Chips kaufen und lustvoll aufknabbern. Doch kommen noch mehr Chips in die Stadt. Die allerdings sind nicht zum Knabbern geeignet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Intel Corporation, einer der gr\u00f6\u00dften Chiphersteller der Welt, will am Rande Stadt f\u00fcr l\u00e4ppische 17 Milliarden, &#8211; nein, in kein Krankenhaus &#8211; sondern in eine Chip- und Halbleiterfabrik investieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun h\u00f6re ich schon wieder die Ignoranten lamentieren: Nicht schon wieder nur halbe Sachen! Da kann man nur Lachen. Endlich werden in Madeburg aus halben Sachen ganze Sachen. Ein kleines, verschmitztes L\u00e4cheln in die Zukunft der Stadt d\u00fcrfte dem Magdeburger schon jetzt gestattet sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Worum geht&#8217;s eigentlich?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otto von Guericke ist verwirrt. Nur die Magdeburger Jungfrau erkennt ihn noch. Nicht mal Till\u2005Eulenspiegel wird seiner gewahr. Gut, er ist nur ein Denkmal und aus Bronze, das ab zu mal vom Sockel steigt. Aber das scheint der Welt in Magdeburg als Grund zu gereichen seine Popularit\u00e4t in Pension zu schicken? Selbst verwirrte Touristen nehmen ihn falsch wahr. Da kann er auch einen trinken gehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zumindest einer merkt, wenn er weg ist. Manni Fest. DAS Magdeburger Urgestein. Aber der will ihm auch nur die Kugel klauen. Da kommt Hauptoberwachtmeister Kn\u00fcppel ins Spiel. Aber nat\u00fcrlich zu sp\u00e4t. Und das hat Folgen. Zum Beispiel Franz Branntwein. Der kann zwar auch nichts ausrichten, aber immer noch mehr als Erdmute. Und so m\u00e4andert die verworrene Story um Sex, Gewalt und Kriminalit\u00e4t undurchschaubar vor sich hin, bis Rettung naht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mr. Bob (Bob) will Magdeburg mit Chips und Halbleitern bereichern. Und das das das frisch gew\u00e4hlte Stadtoberhaupt Misone Norris befl\u00fcgelt, d\u00fcrfte selbst Otto nicht \u00fcberraschen. Nur Mazze und Malte. Aber irgendwas ist ja immer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sicherheitshinweis: F\u00fcr dieses St\u00fcck wurden keine lebenden Kugeln halbiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Es spielen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Marie Matth\u00e4us<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Franziska Hengstmann<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Christian Karius<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Heiko Herfurth<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Sebastian Hengstmann<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Tobias Hengstmann<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">UND<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Frank Hengstmann als MANNI FEST<\/li><\/ul>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Technikmuseum<\/p>\n","protected":false},"author":1,"featured_media":1710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,28,103,115,133,137,132,136,134],"tags":[],"class_list":["post-1709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archiv","category-ensemble","category-10ae_sommertheaterbisher","category-2022-ensemble","category-sebastian-hengstmann","category-christian-karius","category-franziska-hengstmann","category-heiko-spielte-in","category-tobias-hengstmann"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:26:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/posts\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/comments?post=1709"}],"version-history":[{"count":11,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/posts\/1709\/revisions"}],"predecessor-version":[{"id":2301,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/posts\/1709\/revisions\/2301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/media\/1710"}],"wp:attachment":[{"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/media?parent=1709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/categories?post=1709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hengstmanns.de\/WP\/wp-json\/wp\/v2\/tags?post=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}